{"id":29012,"date":"2020-06-05T11:39:06","date_gmt":"2020-06-05T14:39:06","guid":{"rendered":"https:\/\/www.fhycs.unam.edu.ar\/portada\/?p=29012"},"modified":"2020-06-05T11:39:06","modified_gmt":"2020-06-05T14:39:06","slug":"la-fhycs-unam-tiene-un-nuevo-doctor-en-ciencias-humanas-y-sociales","status":"publish","type":"post","link":"https:\/\/www.fhycs.unam.edu.ar\/portada\/la-fhycs-unam-tiene-un-nuevo-doctor-en-ciencias-humanas-y-sociales\/","title":{"rendered":"La FHyCS-UNaM tiene un nuevo Doctor en Ciencias Humanas y Sociales"},"content":{"rendered":"<p style=\"text-align: justify;\">Se trata de <strong>Marcelo Graciosi<\/strong>, quien este jueves 4 de junio de 2020 defendi\u00f3 exitosamente de forma virtual su Tesis Doctoral <strong>&#8220;Hegemon\u00eda y Gubernamentalidad en el territorio de Corrientes en el periodo 1993-1999&#8221;<\/strong>, con la presencia del comit\u00e9 evaluador, su directora, miembros de la carrera y compa\u00f1eros.<!--more--><\/p>\n<p style=\"text-align: justify;\">El trabajo, dirigido por la<strong> Dra. Susana Murillo<\/strong> y evaluado por la <strong>Dra. Ana Pratessi<\/strong>, la <strong>Dra. Yolanda Urquiza<\/strong> y el <strong>Dr. Ricardo Biazzi<\/strong>, analiz\u00f3 las caracter\u00edsticas pol\u00edticas e ideol\u00f3gicas de la provincia de Corrientes durante la instauraci\u00f3n del neoliberalismo, partiendo desde sus or\u00edgenes como parte del Estado Nacional Argentino.<\/p>\n<p style=\"text-align: justify;\">El Doctorado en Ciencias Humanas y Sociales de la Universidad Nacional de Misiones agradece la participaci\u00f3n y colaboraci\u00f3n de los jurados, como as\u00ed tambi\u00e9n del p\u00fablico asistente en modalidad virtual y felicita al Dr. Graciosi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se trata de Marcelo Graciosi, quien este jueves 4 de junio de 2020 defendi\u00f3 exitosamente de forma virtual su Tesis Doctoral &#8220;Hegemon\u00eda y Gubernamentalidad en el territorio de Corrientes en el periodo 1993-1999&#8221;, con la presencia del comit\u00e9 evaluador, su directora, miembros de la carrera y compa\u00f1eros.<\/p>\n","protected":false},"author":6,"featured_media":29014,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"extendify_custom_stylesheet":""},"categories":[37,128,3075,2676,36,794],"tags":[3905,4821,4820,5,3809,3901,4819,4822,4818],"_links":{"self":[{"href":"https:\/\/www.fhycs.unam.edu.ar\/portada\/wp-json\/wp\/v2\/posts\/29012"}],"collection":[{"href":"https:\/\/www.fhycs.unam.edu.ar\/portada\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fhycs.unam.edu.ar\/portada\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fhycs.unam.edu.ar\/portada\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fhycs.unam.edu.ar\/portada\/wp-json\/wp\/v2\/comments?post=29012"}],"version-history":[{"count":3,"href":"https:\/\/www.fhycs.unam.edu.ar\/portada\/wp-json\/wp\/v2\/posts\/29012\/revisions"}],"predecessor-version":[{"id":29016,"href":"https:\/\/www.fhycs.unam.edu.ar\/portada\/wp-json\/wp\/v2\/posts\/29012\/revisions\/29016"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fhycs.unam.edu.ar\/portada\/wp-json\/wp\/v2\/media\/29014"}],"wp:attachment":[{"href":"https:\/\/www.fhycs.unam.edu.ar\/portada\/wp-json\/wp\/v2\/media?parent=29012"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fhycs.unam.edu.ar\/portada\/wp-json\/wp\/v2\/categories?post=29012"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fhycs.unam.edu.ar\/portada\/wp-json\/wp\/v2\/tags?post=29012"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}